{"id":104,"date":"2019-03-25T23:16:39","date_gmt":"2019-03-25T22:16:39","guid":{"rendered":"http:\/\/kurse.textapotheke.de\/?page_id=104"},"modified":"2021-12-15T13:20:02","modified_gmt":"2021-12-15T12:20:02","slug":"anmeldeseite-textrezepte","status":"publish","type":"page","link":"https:\/\/kurse.textapotheke.de\/index.php\/anmeldeseite-textrezepte\/","title":{"rendered":"Anmeldeseite Textrezepte"},"content":{"rendered":"<h1 id=\"tab-con-1\" style=\"text-align: center;\"><span><strong><span style=\"\">Gratis Textwissen&nbsp;<\/span><\/strong><\/span><span><strong><span style=\"\">f\u00fcr&nbsp;<\/span><\/strong><\/span><span><strong><span style=\"\"><\/span><\/strong><\/span><span><strong><span style=\"\">deinen Erfolg!<\/span><\/strong><\/span><\/h1>\n<h1><span><strong><span><span>Du willst endlich mit deinen Texten verkaufen?&nbsp;<\/span><\/span><\/strong><\/span><span><span><strong><span><span><\/span><\/span><\/strong><\/span><\/span><span><strong><span><span><span>Perfekt, denn als Abonnent*in erh\u00e4ltst du exklusiv:<\/span><\/span><\/span><\/strong><\/span><\/h1>\n<ul>\n<li>                    <span>Extrem effektive Schreib-Werkzeuge f\u00fcr deine individuellen Werbetexte &#8211; f\u00fcr dich und dein Business<\/span><\/li>\n<li>                    <span>Tipps und Tricks zu Storytelling, Contentmapping und dem Schreiben im Web 2.0<\/span><\/li>\n<li>                    <span>Exklusive Infos \u00fcber Angebote, neue Podcast-Folgen, Do\u00b4s &amp; Dont\u00b4s und Blicke hinter die Kulissen.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.textapotheke.de\/datenschutz\" target=\"_blank\" rel=\"noopener\">Datenschutz<\/a> &#8211; <a href=\"http:\/\/www.textapotheke.de\/impressum\" target=\"_blank\" rel=\"noopener\">Impressum<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gratis Textwissen&nbsp;f\u00fcr&nbsp;deinen Erfolg! Du willst endlich mit deinen Texten verkaufen?&nbsp;Perfekt, denn als Abonnent*in erh\u00e4ltst du exklusiv: Extrem effektive Schreib-Werkzeuge f\u00fcr deine individuellen Werbetexte &#8211; f\u00fcr dich und dein Business Tipps und Tricks zu Storytelling, Contentmapping und dem Schreiben im Web 2.0 Exklusive Infos \u00fcber Angebote, neue Podcast-Folgen, Do\u00b4s &amp; Dont\u00b4s und Blicke hinter die Kulissen. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages\/104"}],"collection":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":32,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages\/104\/revisions"}],"predecessor-version":[{"id":1428,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages\/104\/revisions\/1428"}],"wp:attachment":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/media?parent=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}