{"id":239,"date":"2019-11-22T12:15:12","date_gmt":"2019-11-22T11:15:12","guid":{"rendered":"http:\/\/kurse.textapotheke.de\/?page_id=239"},"modified":"2021-12-09T14:43:51","modified_gmt":"2021-12-09T13:43:51","slug":"kurs-instamin","status":"publish","type":"page","link":"https:\/\/kurse.textapotheke.de\/index.php\/alle-kurse-und-workshops\/kurs-instamin\/","title":{"rendered":"Kurs Instamin"},"content":{"rendered":"<h1 id=\"tab-con-11\" style=\"text-align: left;\"><span style=\"color: rgb(255, 255, 255); font-size: 90px;\">\u200b<\/span><\/h1>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 50px;\">CONTENT STATT CORONA!<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span>Du willst nicht mehr warten. Du willst endlich durchstarten &#8211; und zwar mit einer klaren Linie, mit Profil, Authentizit\u00e4t und vor allem: mit Erfolg!&nbsp;<\/span><span>Dann nimm Platz und deine Feder in die Hand, denn hier bist du goldrichtig! In INSTAMIN zeige ich dir, wie du dein Business sichtbar und reichweitenstark auf Instagram machst, die richtigen Kunden anziehst und dich optimal positionierst. Deine Idee sollte es dir Wert sein. G<span style=\"font-size: 23px;\">emeinsam machen wir sie gro\u00df!<\/span><\/span><span>\u200b<\/span><span style=\"color: rgb(226, 176, 7); font-size: 45px; font-family: Lato; font-weight: 400;\"><strong><span>INSTAMIN IST RICHTIG F\u00dcR:<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><strong>Selbstst\u00e4ndige &amp; MacherInnen<\/strong><\/p>\n<p style=\"text-align: center;\">Du willst leicht neue Kunden gewinnen und dir die riesigen Chancen von Instagram nicht entgehen lassen.<\/p>\n<p style=\"text-align: center;\"><strong>Strategie-Suchende und Umsetzende<\/strong><\/p>\n<p style=\"text-align: center;\">Du willst einen festen und erprobten Plan und damit direkt in die Umsetzung gehen. Ohne Trial &amp; Error!<\/p>\n<p style=\"text-align: center;\"><strong>Zeit-SparerInnen und Freiheits-Liebende<\/strong><\/p>\n<p style=\"text-align: center;\">Du willst Zeit und Kosten sparen, Prozesse automatisieren und dadurch vor allem eines: Freiheit gewinnen!<\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-3\" style=\"text-align: center;\">Der Kurs wird freigeschaltet in:<\/h3>\n<h3><strong>Jetzt eintragen und anfangen!<\/strong><\/h3>\n<p>Trage dich unverbindlich in die Warteliste ein und profitiere vom Einf\u00fchrungspreis! (nur 249,00 Euro statt 399,00 Euro ab 02.01.2022!)<\/p>\n<p>quote-left<\/p>\n<p>\u201c<span>W<\/span><span>ir k\u00f6nnen nur verkaufen, wenn wir sichtbar sind. Dein Angebot, deine Idee, deine Leidenschaft ist es wert, gesehen zu werden, denn ganz sicher gibt es viele Menschen, die von deiner Leistung profitieren werden. Sie zu finden, ist das Ziel dieses Kurses. Mein Kurs bringt dich und deine Follower zusammen und schafft eine echte Verbindung. Dabei<\/span> geht nicht nur um Follower und st\u00e4ndiges Wachstum. Es geht um Qualit\u00e4t in Text und Bild. Wenn du mehr willst, als den Schall und Rauch von Zahlen, ist Instamin das richtige f\u00fcr dich.\u201d<\/p>\n<p>Jennifer Ingmann<\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-3\" style=\"text-align: center;\">Warum du Instamin brauchst:<\/h3>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-3\" style=\"text-align: left;\">1. Du willst dich perfekt positionieren<\/h3>\n<p>Neues Medium, viele Fragen, keine Motivation. Wenn du mit deinem Unternehmen bei Instagram starten willst, beginne direkt strategisch und durchdacht. Von der Vertextung deiner Instagram-Biografie bis zum Storytelling in Stories und Co. Das klappt nur mit der richtigen Positionierung und dem Fokus auf richtig gutem Content &#8211; mein Spezialgebiet als Werbetexterin.<\/p>\n<p><span style=\"width: 100%;\"><img loading=\"lazy\" alt=\"\" width=\"500\" height=\"500\" title=\"tex-3 Kopie 9\" data-id=\"188\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/03\/tex-3-Kopie-9.png\" style=\"width: 100%;\"><\/span><\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-4\" style=\"text-align: left;\">2. Du willst verkaufen. Basta!<\/h3>\n<p>Bling bling ist nicht dein Ding. Du hast ein tolles Business, das eine bombastische Reichweite verdient hat. Content is king &#8211; nutze diese Marketingweisheit! Als Werbetexterin und freie Journalistin zeige ich dir, wie du bei Instagram texten solltest, um Leser, Kunden &amp; Kooperationspartner von dir zu \u00fcberzeugen.&nbsp;<\/p>\n<p><span style=\"width: 100%;\"><img loading=\"lazy\" alt=\"\" width=\"500\" height=\"500\" title=\"tex-3 Kopie 8\" data-id=\"178\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/03\/tex-3-Kopie-8.png\" style=\"width: 100%;\"><\/span><\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-5\" style=\"text-align: left;\">3. Du hast keine Zeit f\u00fcr Fehler<\/h3>\n<p>Du willst keine Zeit vergeuden und mit m\u00f6glichst viel Wissen starten. Welche Apps sind sinnvoll? Wie plane ich mein Contentmarketing? Meine Textvorlagen, Checklisten und Muster helfen dir bei der Planung und Organisation deines Instagram-Marketings. Von Textbausteinen bis zum Redaktionsplan!&nbsp;<\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-6\" style=\"text-align: left;\">4. Du willst ein Rundum-Paket<\/h3>\n<p>Gutes Marketing h\u00f6rt beim Texten nat\u00fcrlich nicht auf. Das richtige Design, selbst erstellte Presets, Storysticker &#8211; kurzum ein einheitliches Corporate Design &#8211; sind mindestens genauso wichtig. Ich werde dich in die Anwendung von passenden Tools einf\u00fchren, mit denen du deine Designs ganz einfach selbst erstellen und einsetzen kannst. Mach dich unabh\u00e4ngig!<\/p>\n<p><span style=\"width: 100%;\"><img loading=\"lazy\" alt=\"\" width=\"500\" height=\"500\" title=\"tex-3 Kopie 10\" data-id=\"179\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/03\/tex-3-Kopie-10.png\" style=\"width: 100%;\"><\/span><\/p>\n<p><span style=\"width: 100%;\"><img loading=\"lazy\" alt=\"\" width=\"500\" height=\"500\" title=\"tex-5\" data-id=\"177\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/03\/tex-5.png\" style=\"width: 100%;\"><\/span><\/p>\n<h3><strong>Jetzt eintragen und anfangen!<\/strong><\/h3>\n<p>Trage dich unverbindlich in die Warteliste ein und profitiere vom Einf\u00fchrungspreis! (nur 249,00 Euro!)<\/p>\n<p><span><strong><span>Worte sind&nbsp;<\/span><\/strong><\/span><span><strong><span>mein Warum.<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: rgb(86, 81, 81);\">Worte sind machtvoll. Worte bedeuten Kraft. Worte sind grenzenlos. Ihre Kraft zu kennen und meine ganz eigene Geschichte und die meiner Kund*innen daraus zu schreiben, ist seit 2009 mein Weg. Ich wei\u00df, <span>welche H\u00fcrden es im eigenen Business zu nehmen gilt. Ich wei\u00df aber auch, wie einfach es sein kann<\/span><span>, wenn wir strukturiert und fokussiert an unseren Worten arbeiten. Und vor allem: wenn wir unser &#8222;Warum&#8220; kennen und es anderen erz\u00e4hlen k\u00f6nnen. Damit entz\u00fcnden wir Feuer, statt Geld zu verbrennen.<\/span><\/span><\/p>\n<p><span style=\"color: rgb(86, 81, 81);\"><span>&nbsp;Rock on &#8211; wir packen\u00b4s an!<\/span><\/span><\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-3\" style=\"text-align: center;\">Deine Module zum Erfolg:<\/h3>\n<p style=\"text-align: center;\"><span>\u200b<\/span><\/p>\n<p><span><img loading=\"lazy\" alt=\"\" width=\"831\" height=\"820\" title=\"AdobeStock_237380527\" data-id=\"392\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/08\/AdobeStock_237380527.png\"><\/span><\/p>\n<p><strong>Basiswissen<\/strong><\/p>\n<p style=\"text-align: left;\">Hier wirst du deine Unternehmensziele f\u00fcr Instagram festlegen, deine Zielgruppe definieren, deine Bio perfekt texten und dein Account-Grundger\u00fcst erstellen.&nbsp;<\/p>\n<p><span style=\"width: 100%;\"><img loading=\"lazy\" alt=\"\" width=\"844\" height=\"800\" title=\"AdobeStock_139939130\" data-id=\"388\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/08\/AdobeStock_139939130.png\" style=\"width: 100%;\"><\/span><\/p>\n<p><strong>Starke Texte<\/strong><\/p>\n<p style=\"text-align: left;\">Mein Spezialgebiet! Ich zeige dir, wie du deine Inhalte verkaufsstark textest, ohne aufdringlich zu wirken. Und wie du mit Storytelling und meinen Textwerkzeugen wertvollen Content schaffst. Einfacher geht es nicht!<\/p>\n<p style=\"text-align: left;\">\n<p><span><img loading=\"lazy\" alt=\"\" width=\"852\" height=\"829\" title=\"AdobeStock_116671774\" data-id=\"386\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/08\/AdobeStock_116671774.png\"><\/span><\/p>\n<p><strong>Wow-Bilder<\/strong><\/p>\n<p style=\"text-align: left;\">Wie ein durchg\u00e4ngiges Bildkonzept entsteht und wie Bilder und Texte aufeinander zugeschnitten werden, erf\u00e4hrst du in diesem Modul.. Ich gebe dir wertvolle Tipps und f\u00fchre dich in die Verwendung eigener Presets ein.<\/p>\n<p><span><img loading=\"lazy\" alt=\"\" width=\"780\" height=\"775\" title=\"AdobeStock_194379672\" data-id=\"390\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/08\/AdobeStock_194379672.png\"><\/span><\/p>\n<p>Instagram<strong>&nbsp;Stories<\/strong><\/p>\n<p style=\"text-align: left;\">Instagram Stories sind ein m\u00e4chtiges Werkzeug f\u00fcr (fast spontanen) Content. Mit welchen Apps du arbeiten solltest und wie du ein stringentes Story-Konzept f\u00e4hrst, verrate ich dir in diesem Modul.<\/p>\n<p style=\"text-align: left;\">\n<p><span><img loading=\"lazy\" alt=\"\" width=\"855\" height=\"846\" title=\"AdobeStock_129110344\" data-id=\"387\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/08\/AdobeStock_129110344.png\"><\/span><\/p>\n<p><strong>Eigene Wow-Designs<\/strong><\/p>\n<p style=\"text-align: left;\">Gebrandete Story Sticker, Highlight-Cover, das perfekte Media-Kit f\u00fcr Kooperationen: es sind die kleinen Dinge, die dein Corporate Design perfektionieren. Ich zeige dir, wie du deine Designs einfach selbst erstellst und wie einfach das geht!<\/p>\n<p style=\"text-align: left;\">\n<p><span><img loading=\"lazy\" alt=\"\" width=\"756\" height=\"749\" title=\"AdobeStock_178083672\" data-id=\"389\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2019\/08\/AdobeStock_178083672.png\"><\/span><\/p>\n<p><strong>Redaktionsplanung<\/strong><\/p>\n<p style=\"text-align: left;\">Mein Spezialgebiet! Marketing ist bekanntlich ein Marathon und kein Sprint. Mit einer guten Redaktionsplanung und Contentmapping machst du dir die Erstellung deines Contents ganz einfach. Versprochen!<\/p>\n<p style=\"text-align: center;\"><strong>Dieser Kurs ist perfekt&nbsp;<\/strong><strong>f\u00fcr dich, wenn du:<\/strong><\/p>\n<p><span style=\"font-size: 19px;\"><\/span><\/p>\n<ul>\n<li><span style=\"font-size: 20px;\"><strong><span style=\"color: rgb(253, 253, 255);\">Instagram&nbsp;<\/span><\/strong><span style=\"color: rgb(253, 253, 255);\"><strong>effektiv f\u00fcr dein Business nutzen willst<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span style=\"font-size: 20px;\"><strong>hochwertigen Content produzieren &nbsp;willst<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span><strong>verkaufsstarkes Storytelling lernen willst<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span style=\"font-size: 20px;\"><strong>deinen Auftritt deiner CI anpassen willst<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span style=\"font-size: 20px;\"><strong>verkaufsstarke Texte texten m\u00f6chtest<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span style=\"font-size: 20px;\"><strong>starke Fotos produzieren willst<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span><strong>Mehrwert liefern willst<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span><strong>hochwertige Follower gewinnen willst<\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span style=\"font-size: 20px;\"><strong><strong>praktische Checklisten und Muster ben\u00f6tigst<\/strong><\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span style=\"font-size: 20px;\"><strong><strong>Individuelle Presets nutzen willst<\/strong><\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span><strong><strong>Perfekte Textvorlagen brauchst<\/strong><\/strong><\/span><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><strong><span>nicht stundenlang in der App h\u00e4ngen m\u00f6chtest<\/span><\/strong><\/span><\/li>\n<li><span style=\"color: rgb(253, 253, 255);\"><span><strong>&nbsp;fix den perfekten Redaktionsplan erstellen willst<\/strong><\/span><\/span><\/li>\n<\/ul>\n<p>__CONFIG_group_edit__{&#8222;kcanr8vu&#8220;:{&#8222;name&#8220;:&#8220;Quote Image&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Image %s&#8220;},&#8220;kcanried&#8220;:{&#8222;name&#8220;:&#8220;Text&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Text %s&#8220;},&#8220;kcanrn1x&#8220;:{&#8222;name&#8220;:&#8220;Name&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Text %s&#8220;},&#8220;kcanrtg9&#8243;:{&#8222;name&#8220;:&#8220;Text Box&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Content Box %s&#8220;},&#8220;kcc7n14o&#8220;:{&#8222;name&#8220;:&#8220;Image&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Image %s&#8220;},&#8220;kcc7ngdp&#8220;:{&#8222;name&#8220;:&#8220;Testimonial Box&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Content Box %s&#8220;},&#8220;kcc7nn63&#8243;:{&#8222;name&#8220;:&#8220;Main Column&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Column %s&#8220;},&#8220;kcc7nucy&#8220;:{&#8222;name&#8220;:&#8220;Main Columns&#8220;,&#8220;singular&#8220;:&#8220;&#8211; Columns %s&#8220;}}__CONFIG_group_edit__<\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-3\" style=\"text-align: center;\">Was meine Kunden sagen:<\/h3>\n<p><span style=\"width: 100%;\"><img alt=\"\" data-id=\"818\" width=\"232\" data-init-width=\"110\" height=\"232\" data-init-height=\"110\" title=\"image001\" loading=\"lazy\" src=\"https:\/\/kurse.textapotheke.de\/wp-content\/uploads\/2020\/03\/image001.png\" data-width=\"52\" data-height=\"52\" style=\"width: 100%;\"><\/span><span><img alt=\"\" data-id=\"60513\" width=\"37\" data-init-width=\"37\" height=\"28\" data-init-height=\"28\" title=\"Quote_left marks\" loading=\"lazy\" src=\"\/\/kurse.textapotheke.de\/wp-content\/uploads\/tcb_content_templates\/testimonial\/images\/Quote_left-marks.png\" data-width=\"37\" data-height=\"28\" style=\"\"><\/span><\/p>\n<p>Jenny ist eine echte Expertin auf dem Gebiet und ich habe sehr viel dazugelernt. Vorher war Instagram f\u00fcr mich eher ein Buch mit sieben Siegeln&#8230;.Daher meine absolute Empfehlung f\u00fcr jeden, der Instagram von der Pike auf verstehen und nutzen m\u00f6chte!<\/p>\n<h4><span>Eva Stiekema &#8211; Linguavision und New Work Moms&nbsp;<\/span><\/h4>\n<p><span>\u200b<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: &quot;Open Sans&quot;; font-weight: 400;\"><span><span style=\"color: rgb(255, 255, 255);\">Was du bekommst:<\/span><\/span><\/span><\/p>\n<ul>\n<li><span style=\"font-family: &quot;Open Sans&quot;; font-weight: 400;\"><span style=\"font-size: 20px;\"><span style=\"color: rgb(255, 255, 255);\">Exklusives Videomaterial, spannende Podcastfolgen und erprobte Checklisten, damit du direkt starten kannst.&nbsp;<\/span><\/span><\/span><\/li>\n<li><span style=\"font-weight: 400;\"><span style=\"font-family: 'Open Sans';\"><span style=\"color: rgb(255, 255, 255);\"><span style=\"font-size: 20px;\">Eine strategische Planung deiner Instagram-Aktivit\u00e4ten &#8211; inklusive meiner Texter-Formel!<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"font-weight: 400;\"><span style=\"font-family: 'Open Sans';\"><span style=\"color: rgb(255, 255, 255);\"><span style=\"font-size: 20px;\">Flexible Lern- und Umsetzungszeiten!&nbsp;<\/span><\/span><\/span><\/span><span style=\"font-weight: 400;\"><span style=\"font-family: 'Open Sans';\"><span style=\"color: rgb(255, 255, 255);\"><span style=\"font-size: 20px;\">Du kannst deinen Kurs beginnen, wann immer du willst.<\/span><\/span><\/span><\/span><\/li>\n<li><span style=\"font-family: &quot;Open Sans&quot;; font-weight: 400;\"><span style=\"color: rgb(255, 255, 255);\"><span style=\"font-size: 20px;\">Know-how f\u00fcr die Praxis! Damit kommst du direkt in die Umsetzung und verlierst keine Zeit.<\/span><\/span><\/span><span style=\"font-family: &quot;Open Sans&quot;; font-weight: 400;\"><span style=\"color: rgb(255, 255, 255);\"><span style=\"font-size: 20px;\"><\/span><\/span><\/span><\/li>\n<\/ul>\n<h3><strong>Jetzt eintragen und anfangen!<\/strong><\/h3>\n<p>Trage dich unverbindlich in die Warteliste ein und profitiere vom Einf\u00fchrungspreis! (nur 249,00 Euro statt 399,00 Euro ab 02.01.2022!)<\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-3\" style=\"text-align: center;\">Wie es jetzt weiter geht:<\/h3>\n<p><span><strong><strong>Kaufe meinen Kurs (sobald er buchbar ist)<\/strong><\/strong><\/span><\/p>\n<p>Wenn du dich in die Warteliste eintr\u00e4gst, profitierst du auf jeden Fall vom g\u00fcnstigen Einf\u00fchrungspreis. Diesen wird es so nicht mehr geben.<\/p>\n<p><span><strong>Lerne wann und wo du willst<\/strong><\/span><\/p>\n<p>Meinen Kurs kannst du ganz flexibel machen. Wann und wo du willst! Ohne Stress und Hektik, daf\u00fcr mit exzellentem Know-How vom Content-Profi.<\/p>\n<p><strong>Setze einfach und strategisch um<\/strong><\/p>\n<p>Du kommst schon im ersten Modul in die Umsetzung. Schritt f\u00fcr Schritt. Damit du keine Zeit verlierst, sondern direkt durchstarten kannst.&nbsp;<\/p>\n<h3 data-tve-custom-colour=\"79299423\" id=\"tab-con-3\" style=\"text-align: center;\">Denn am Ende kaufen wir immer von Menschen.&nbsp;<\/h3>\n<p><span><strong><span style=\"color: rgb(226, 176, 7);\">\u200b<\/span><\/strong><\/span><\/p>\n<p><span>Z<\/span><span>eit ist nicht nur unter New Work Moms die wichtigste Ressource. Sie m\u00f6glichst effektiv einzusetzen, ist der Schl\u00fcssel zu deinem erfolgreichen Business. Verlier keine Zeit, warte nicht, hadere nicht &#8211; &nbsp;steig endlich ein. Jetzt! &nbsp;Und vor allem: zeig dich! Denn am Ende kaufen wir immer von Menschen! Ich freue mich, wenn du dabei bist!<\/span><\/p>\n<p><span>\u200b<\/span><\/p>\n<p><span>\u200b<\/span><\/p>\n<p><span>\u200b<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u200b CONTENT STATT CORONA! Du willst nicht mehr warten. Du willst endlich durchstarten &#8211; und zwar mit einer klaren Linie, mit Profil, Authentizit\u00e4t und vor allem: mit Erfolg!&nbsp;Dann nimm Platz und deine Feder in die Hand, denn hier bist du goldrichtig! In INSTAMIN zeige ich dir, wie du dein Business sichtbar und reichweitenstark auf Instagram [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1365,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages\/239"}],"collection":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":144,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages\/239\/revisions"}],"predecessor-version":[{"id":1368,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages\/239\/revisions\/1368"}],"up":[{"embeddable":true,"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/pages\/1365"}],"wp:attachment":[{"href":"https:\/\/kurse.textapotheke.de\/index.php\/wp-json\/wp\/v2\/media?parent=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}